{"id":37,"date":"2021-03-23T06:10:31","date_gmt":"2021-03-23T06:10:31","guid":{"rendered":"https:\/\/www.magicien-magie.com\/blog\/?p=37"},"modified":"2021-04-21T13:51:37","modified_gmt":"2021-04-21T13:51:37","slug":"le-pouvoir-et-lart-magique","status":"publish","type":"post","link":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/","title":{"rendered":"Le pouvoir et l&rsquo;art magique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un <strong>magicien<\/strong> f\u00e9ru d\u2019histoire expliqua un jour \u00e0 un coll\u00e8gue comment des peuplades sans discipline et sans armes perfectionn\u00e9es ont pu r\u00e9sister si longtemps \u00e0 la bravoure des troupes fran\u00e7aise et au feu meurtrier des canons. Un tour de prestidigitation expliquera cette r\u00e9sistance opini\u00e2tre. Que cette assertion n&rsquo;am\u00e8ne pas sur les l\u00e8vres un sourire d&rsquo;incr\u00e9dulit\u00e9, ce n&rsquo;est pas une boutade d&rsquo;un esprit ami de la plaisanterie, mais l&rsquo;expression de la plus stricte v\u00e9rit\u00e9.<br><br>Chez les Arabes, les Marabouts exer\u00e7aient un pouvoir sans bornes et la d\u00e9sob\u00e9issance \u00e0 leurs ordres \u00e9tait s\u00e9v\u00e8rement punie ici-bas et dans l&rsquo;autre vie, dit-on. A l&rsquo;\u00e9poque de la conqu\u00eate de l&rsquo;Alg\u00e9rie, les Marabouts r\u00e9unissaient leurs guerriers autour d&rsquo;un baquet rempli d&rsquo;eau, et soudain apparaissaient dans le liquide les images des soldats fran\u00e7ais, apparition de courte dur\u00e9e, car ces repr\u00e9sentations s&rsquo;\u00e9vanouissaient bient\u00f4t. N&rsquo;\u00e9tait-ce pas le pr\u00e9sage certain de la d\u00e9faite et de la fuite des fran\u00e7ais ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Arabes cr\u00e9dules \u00e9taient fascin\u00e9s et fanatis\u00e9s par ces exp\u00e9riences, et ils couraient au combat avec l&rsquo;intr\u00e9pidit\u00e9 que donne l&rsquo;assurance de la victoire. Echecs, d\u00e9faites, rien ne les d\u00e9sillusionnait. Le truc des Marabouts est facile \u00e0 deviner.&nbsp; Des images d&rsquo;Epinal repr\u00e9sentant des soldats fran\u00e7ais \u00e9taient coll\u00e9es dans la paume de leurs mains, elles se reproduisaient dans l&rsquo;eau quand les marabouts tenaient leurs mains au-dessus du baquet. Elles disparaissaient lorsque par un imperceptible coup de genou l&rsquo;eau du baquet se troublait. Qui donc aurait jamais pens\u00e9 que l&rsquo;art de la magie serait d\u00e9tourn\u00e9 de son but pacifique pour entretenir les fureurs de la guerre ?<br><br>Quittons ces sc\u00e8nes de carnage et venons au milieu de la Sib\u00e9rie rencontrer une peuplade Tchouktchis qui a le bonheur de vivre dans un climat d\u00e9sol\u00e9, sur les bords tr\u00e8s peu enchanteurs du d\u00e9troit de B\u00e9ring. Il&nbsp; semble que ce nom devrait tenter un artiste qui voudrait changer son nom patronymique et adopter un pseudonyme \u00e0 sensation. Tchouktchis n&rsquo;est-il pas rempli d&rsquo;une douceur et d&rsquo;une harmonie dont tout le monde doit demeurer d&rsquo;accord ? Quel succ\u00e8s foudroyant obtiendrait une s\u00e9ance donn\u00e9e par les chouktchis ? Elle \u00e9lectriserait les temp\u00e9raments les plus apathiques, elle enflammerait les c\u0153urs les plus indiff\u00e9rents. Le soir, la foule s&rsquo;\u00e9craserait \u00e0 la porte du spectacle.<br><br>Dans la relation de son voyage, un explorateur \u00e9crit ce qui suit au sujet des Tchouktchis :<br><br>Les naturels se montraient affables, complaisants et cherchant \u00e0 payer de la m\u00eame monnaie nos cajoleries et nos badinages. Je frappais doucement de la main en signe d&rsquo;amiti\u00e9, sur la joue d&rsquo;un vigoureux Tchouktchis et je re\u00e7us en r\u00e9ponse un soufflet qui faillit me renverser, Revenu de mon \u00e9tonnement, je vis devant moi mon homme avec un visage riant, exprimant la satisfaction d&rsquo;avoir su montrer son savoir-vivre. Il avait voulu taper doucement, mais d&rsquo;une main habitu\u00e9e \u00e0 ne taper que des rennes.<br><br>Nous f\u00fbmes t\u00e9moins des preuves d&rsquo;adresse donn\u00e9es par un Tchouktchis qui passait pour Chaman ou sorcier. Il passa derri\u00e8re un rideau d&rsquo;o\u00f9 l&rsquo;on entendit bient\u00f4t sortir une voix semblable \u00e0 un hurlement, tandis que de petits coups \u00e9taient frapp\u00e9s sur un tambourin avec un fanon de baleine. Le rideau lev\u00e9, on vit le sorcier se balancer et renforcer sa voix et ses coups sur le tambour qu&rsquo;il tenait pr\u00e8s de l&rsquo;oreille. Alors, il jeta sa pelisse et se mit nu jusqu&rsquo;\u00e0 la ceinture. Il prit une pierre polie qu&rsquo;il donna \u00e0 tenir \u00e0 L\u00fctk\u00e9, la reprit, et tandis qu&rsquo;il faisait passer une main par dessus l&rsquo;autre, la pierre disparut. Montrant une tumeur qu&rsquo;il avait au coude, il pr\u00e9tendit que la pierre \u00e9tait \u00e0 cet endroit puis il fit voyager la tumeur sur le c\u00f4t\u00e9 et apr\u00e8s avoir extrait la pierre, il affirma que l&rsquo;issue du voyage serait heureuse.<br><br>On f\u00e9licita le sorcier sur son adresse, et on lui fit pr\u00e9sent d&rsquo;un couteau. Le prenant d&rsquo;une main, il tira sa langue et se mit \u00e0 la couper. Sa bouche se remplit de sang. Enfin, apr\u00e8s avoir tout \u00e0 fait coup\u00e9 sa langue. il en montra le morceau dans la main. Ici le rideau tomba : l&rsquo;adresse du prestidigitateur n&rsquo;allait pas plus loin. Comment, l&rsquo;&nbsp;illustre peut donner l&rsquo;illusion d&rsquo;une pierre escamot\u00e9e courant sous la peau le long du bras et celle de la langue qui parait coup\u00e9e, n&rsquo;est pas une preuve suffisante d&rsquo;adresse ?<br><br>Avec leurs restrictions, ces explorateurs avec leur vision que la plus petite banquise ou le moindre rocher emp\u00eachent d&rsquo;aller plus loin ont d\u00e9former ce qu&rsquo;ils ont sembl\u00e9 avoir vu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un magicien f\u00e9ru d\u2019histoire expliqua un jour \u00e0 un coll\u00e8gue comment des peuplades sans discipline et sans armes perfectionn\u00e9es ont pu r\u00e9sister si longtemps \u00e0 &hellip; <\/p>\n","protected":false},"author":3,"featured_media":38,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-37","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chronique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le pouvoir et l&#039;art magique - Blog magie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le pouvoir et l&#039;art magique - Blog magie\" \/>\n<meta property=\"og:description\" content=\"Un magicien f\u00e9ru d\u2019histoire expliqua un jour \u00e0 un coll\u00e8gue comment des peuplades sans discipline et sans armes perfectionn\u00e9es ont pu r\u00e9sister si longtemps \u00e0 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog magie\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-23T06:10:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-21T13:51:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/03\/pouvoir.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"artiste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"artiste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/\"},\"author\":{\"name\":\"artiste\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#\\\/schema\\\/person\\\/5daf4d489d234d2f5bc62f0d15ca0569\"},\"headline\":\"Le pouvoir et l&rsquo;art magique\",\"datePublished\":\"2021-03-23T06:10:31+00:00\",\"dateModified\":\"2021-04-21T13:51:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/\"},\"wordCount\":841,\"image\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/pouvoir.jpg\",\"articleSection\":[\"Chronique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/\",\"url\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/\",\"name\":\"Le pouvoir et l'art magique - Blog magie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/pouvoir.jpg\",\"datePublished\":\"2021-03-23T06:10:31+00:00\",\"dateModified\":\"2021-04-21T13:51:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#\\\/schema\\\/person\\\/5daf4d489d234d2f5bc62f0d15ca0569\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/pouvoir.jpg\",\"contentUrl\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/pouvoir.jpg\",\"width\":800,\"height\":554,\"caption\":\"pouvoir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/le-pouvoir-et-lart-magique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le pouvoir et l&rsquo;art magique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/\",\"name\":\"Blog magie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#\\\/schema\\\/person\\\/5daf4d489d234d2f5bc62f0d15ca0569\",\"name\":\"artiste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g\",\"caption\":\"artiste\"},\"url\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/author\\\/artiste\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le pouvoir et l'art magique - Blog magie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/","og_locale":"fr_FR","og_type":"article","og_title":"Le pouvoir et l'art magique - Blog magie","og_description":"Un magicien f\u00e9ru d\u2019histoire expliqua un jour \u00e0 un coll\u00e8gue comment des peuplades sans discipline et sans armes perfectionn\u00e9es ont pu r\u00e9sister si longtemps \u00e0 &hellip;","og_url":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/","og_site_name":"Blog magie","article_published_time":"2021-03-23T06:10:31+00:00","article_modified_time":"2021-04-21T13:51:37+00:00","og_image":[{"width":800,"height":554,"url":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/03\/pouvoir.jpg","type":"image\/jpeg"}],"author":"artiste","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"artiste","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/#article","isPartOf":{"@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/"},"author":{"name":"artiste","@id":"https:\/\/www.magicien-magie.com\/blog\/#\/schema\/person\/5daf4d489d234d2f5bc62f0d15ca0569"},"headline":"Le pouvoir et l&rsquo;art magique","datePublished":"2021-03-23T06:10:31+00:00","dateModified":"2021-04-21T13:51:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/"},"wordCount":841,"image":{"@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/03\/pouvoir.jpg","articleSection":["Chronique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/","url":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/","name":"Le pouvoir et l'art magique - Blog magie","isPartOf":{"@id":"https:\/\/www.magicien-magie.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/#primaryimage"},"image":{"@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/03\/pouvoir.jpg","datePublished":"2021-03-23T06:10:31+00:00","dateModified":"2021-04-21T13:51:37+00:00","author":{"@id":"https:\/\/www.magicien-magie.com\/blog\/#\/schema\/person\/5daf4d489d234d2f5bc62f0d15ca0569"},"breadcrumb":{"@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/#primaryimage","url":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/03\/pouvoir.jpg","contentUrl":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/03\/pouvoir.jpg","width":800,"height":554,"caption":"pouvoir"},{"@type":"BreadcrumbList","@id":"https:\/\/www.magicien-magie.com\/blog\/le-pouvoir-et-lart-magique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.magicien-magie.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le pouvoir et l&rsquo;art magique"}]},{"@type":"WebSite","@id":"https:\/\/www.magicien-magie.com\/blog\/#website","url":"https:\/\/www.magicien-magie.com\/blog\/","name":"Blog magie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.magicien-magie.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.magicien-magie.com\/blog\/#\/schema\/person\/5daf4d489d234d2f5bc62f0d15ca0569","name":"artiste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g","caption":"artiste"},"url":"https:\/\/www.magicien-magie.com\/blog\/author\/artiste\/"}]}},"_links":{"self":[{"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/posts\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":2,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/posts\/37\/revisions"}],"predecessor-version":[{"id":61,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/posts\/37\/revisions\/61"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/media\/38"}],"wp:attachment":[{"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/categories?post=37"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/tags?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}