{"id":274,"date":"2021-07-19T06:10:06","date_gmt":"2021-07-19T06:10:06","guid":{"rendered":"https:\/\/www.magicien-magie.com\/blog\/?p=274"},"modified":"2021-07-19T06:10:10","modified_gmt":"2021-07-19T06:10:10","slug":"quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements","status":"publish","type":"post","link":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/","title":{"rendered":"Quick change ou transformiste : techniques et secrets de changement de v\u00eatements"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le quick change est une discipline pratiqu\u00e9e par des professionnels du changement rapide qui sont appel\u00e9s transformistes. Ces derniers se chargent de changer de costume le plus rapidement possible. Et ceci afin de susciter le trouble dans l\u2019esprit des spectateurs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le m\u00e9tier de transformiste<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Certains tours de magie et et spectacles d\u2019illusion risquent d&rsquo;\u00eatre divulgu\u00e9s. Cela est d\u00fb \u00e0 la mont\u00e9e en puissance du num\u00e9rique qui vulgarise tous leurs secrets. \u00c0 travers des outils comme YouTube, et des sites internet, toute personne qui souhaite d\u00e9couvrir les myst\u00e8res de cette discipline peut le cas \u00e9ch\u00e9ant trouver satisfaction. Le secteur de l\u2019enchantement est devenu plus facile d\u2019acc\u00e8s qu\u2019auparavant. Il faut dire que d\u2019autres disciplines comme le transformisme arrivent \u00e0 garder son authenticit\u00e9 et son myst\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, le transformisme se distingue des autres tours de magie parce qu\u2019il requiert plus d\u2019attention et de temps. Les professionnels qui sont qualifi\u00e9s de transformistes \u00e9voluent dans la discipline qu\u2019on intitule \u00ab\u2009quick change\u2009\u00bb dont la traduction fran\u00e7aise est \u00ab\u2009changement rapide\u2009\u00bb. Il n\u2019est pas souvent rare de trouver d\u2019autres professions qui poss\u00e8dent les m\u00eames termes et appellations destin\u00e9es \u00e0 effectuer des shows.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussi, de nombreuses personnes confondent les artistes transformistes et les artistes dits \u00ab\u2009transgenres\u2009\u00bb. Ils sont \u00e9galement amalgam\u00e9s avec les personnes qui se plaisent \u00e0 incarner des personnes de l\u2019autre sexe. Mais ce qui distingue ceux-ci des transformistes est justement l\u2019aspect de changement rapide de costumes. Ces personnes aiment bien se donner en spectacle dans des cabarets sp\u00e9cialis\u00e9s dans cette discipline.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le principe des spectacles transformistes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les professionnels qui exercent le changement rapide sont consid\u00e9r\u00e9s comme des \u00ab\u2009performeurs\u2009\u00bb. Le but de cette discipline est simple&nbsp;: il faut changer les accoutrements que l\u2019on aborde le plus rapidement possible. G\u00e9n\u00e9ralement, il s\u2019agit de femmes qui doivent changer des robes. Le changement rapide utilise de nombreuses m\u00e9thodes pour ne rien montrer au spectateur. Du coup, les spectateurs n&rsquo;ont pas le temps de se poser des questions ou encore d\u2019essayer de trouver l\u2019illusion, car les changements se font \u00e0 la vitesse de la lumi\u00e8re.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Arturo Brachetti<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"391\" src=\"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/arturi-brachetti.jpg\" alt=\"\" class=\"wp-image-275\" srcset=\"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/arturi-brachetti.jpg 260w, https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/arturi-brachetti-199x300.jpg 199w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Arturo Brachetti est un transformiste qui se fait connaitre en Italie gr\u00e2ce \u00e0 ses performances dans les ann\u00e9es&nbsp;1957. La ville qui accueillit ce talent \u00e9tait la ville de Turin en Italie. Toutefois, il a commenc\u00e9 ses d\u00e9buts en France. L\u00e0-bas il \u00e9tait encore le seul au monde, il a m\u00eame fait de nombreuses innovations dans ce domaine et a en quelque sorte redor\u00e9 le blason de cette discipline qui fut oubli\u00e9 pendant un moment donn\u00e9. Au fil du temps, les int\u00e9r\u00eats pour le changement rapide n\u2019ont fait que grandir. Arturo est alors devenu pendant la raison pour laquelle les gens s\u2019int\u00e9ressaient au Paradis Latin durant cette \u00e9poque. Depuis lors, son \u00e9volution professionnelle a connu un franc succ\u00e8s jusqu\u2019\u00e0 le hisser parmi les meilleurs professionnels venus d\u2019Italie et pr\u00e9sents sur la sc\u00e8ne mondiale et internationale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La posture de l\u00e9gende du changement rapide colle tr\u00e8s bien \u00e0 la peau d\u2019Artur Brachetti. La r\u00e9putation de l&rsquo;artiste le pr\u00e9c\u00e8de (il a la capacit\u00e9 de changer de chaussures, de costumes, de chapeau en l\u2019espace d\u2019un fragment d\u2019instant) dans de nombreux pays et il est consid\u00e9r\u00e9 comme l\u2019une des rares personnes qui ont su susciter un int\u00e9r\u00eat profond pour le quick change. Le monde du \u00ab\u2009performing art visuel\u2009\u00bb n\u2019a plus aucun secret pour lui. Il a cette facilit\u00e9 \u00e0 s\u2019adapter \u00e0 de nombreux styles de productions.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00e9paration d\u2019un num\u00e9ro en couple<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour une petite illustration de la technique du changement rapide, nous allons prendre l\u2019exemple d\u2019un couple. Ces derniers commencent par d\u00e9montrer toute leur pr\u00e9paration \u00e9tape par \u00e9tape. Ce que l\u2019on retient est qu\u2019il faut appliquer certains principes notamment&nbsp;:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avoir un changement radical et contrast\u00e9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cela permet de mieux constater la transformation. il faut prendre des couleurs diff\u00e9rentes, cela permet justement de cr\u00e9er une diff\u00e9rence avec l\u2019ancien costume.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Diff\u00e9rencier les styles et les compositions<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pour r\u00e9ussir un tour de changement rapide, il faut susciter le trouble chez le spectateur. Et cela passe par la transmutation. En effet, il faut tout changer&nbsp;: style, musique, texture afin de monter le changement et la diff\u00e9rence par apport au costume pr\u00e9c\u00e9dent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le quick change est une discipline pratiqu\u00e9e par des professionnels du changement rapide qui sont appel\u00e9s transformistes. Ces derniers se chargent de changer de costume &hellip; <\/p>\n","protected":false},"author":3,"featured_media":276,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-questions-reponses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quick change, changement rapide de costumes<\/title>\n<meta name=\"description\" content=\"Le monde du divertissement est bond\u00e9 d\u2019arts. Il en existe de toutes les sortes. Entre l\u2019illusionnisme, la magie close up et le quick change, les amateurs n\u2019ont pas le temps de s\u2019ennuyer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quick change, changement rapide de costumes\" \/>\n<meta property=\"og:description\" content=\"Le monde du divertissement est bond\u00e9 d\u2019arts. Il en existe de toutes les sortes. Entre l\u2019illusionnisme, la magie close up et le quick change, les amateurs n\u2019ont pas le temps de s\u2019ennuyer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog magie\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-19T06:10:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-19T06:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/changements-rapides.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"artiste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"artiste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/\"},\"author\":{\"name\":\"artiste\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#\\\/schema\\\/person\\\/5daf4d489d234d2f5bc62f0d15ca0569\"},\"headline\":\"Quick change ou transformiste : techniques et secrets de changement de v\u00eatements\",\"datePublished\":\"2021-07-19T06:10:06+00:00\",\"dateModified\":\"2021-07-19T06:10:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/\"},\"wordCount\":775,\"image\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/changements-rapides.jpg\",\"articleSection\":[\"Questions\\\/r\u00e9ponses\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/\",\"url\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/\",\"name\":\"Quick change, changement rapide de costumes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/changements-rapides.jpg\",\"datePublished\":\"2021-07-19T06:10:06+00:00\",\"dateModified\":\"2021-07-19T06:10:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#\\\/schema\\\/person\\\/5daf4d489d234d2f5bc62f0d15ca0569\"},\"description\":\"Le monde du divertissement est bond\u00e9 d\u2019arts. Il en existe de toutes les sortes. Entre l\u2019illusionnisme, la magie close up et le quick change, les amateurs n\u2019ont pas le temps de s\u2019ennuyer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/changements-rapides.jpg\",\"contentUrl\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/changements-rapides.jpg\",\"width\":900,\"height\":600,\"caption\":\"changements rapides\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quick change ou transformiste : techniques et secrets de changement de v\u00eatements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/\",\"name\":\"Blog magie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/#\\\/schema\\\/person\\\/5daf4d489d234d2f5bc62f0d15ca0569\",\"name\":\"artiste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g\",\"caption\":\"artiste\"},\"url\":\"https:\\\/\\\/www.magicien-magie.com\\\/blog\\\/author\\\/artiste\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quick change, changement rapide de costumes","description":"Le monde du divertissement est bond\u00e9 d\u2019arts. Il en existe de toutes les sortes. Entre l\u2019illusionnisme, la magie close up et le quick change, les amateurs n\u2019ont pas le temps de s\u2019ennuyer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/","og_locale":"fr_FR","og_type":"article","og_title":"Quick change, changement rapide de costumes","og_description":"Le monde du divertissement est bond\u00e9 d\u2019arts. Il en existe de toutes les sortes. Entre l\u2019illusionnisme, la magie close up et le quick change, les amateurs n\u2019ont pas le temps de s\u2019ennuyer.","og_url":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/","og_site_name":"Blog magie","article_published_time":"2021-07-19T06:10:06+00:00","article_modified_time":"2021-07-19T06:10:10+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/changements-rapides.jpg","type":"image\/jpeg"}],"author":"artiste","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"artiste","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/#article","isPartOf":{"@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/"},"author":{"name":"artiste","@id":"https:\/\/www.magicien-magie.com\/blog\/#\/schema\/person\/5daf4d489d234d2f5bc62f0d15ca0569"},"headline":"Quick change ou transformiste : techniques et secrets de changement de v\u00eatements","datePublished":"2021-07-19T06:10:06+00:00","dateModified":"2021-07-19T06:10:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/"},"wordCount":775,"image":{"@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/#primaryimage"},"thumbnailUrl":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/changements-rapides.jpg","articleSection":["Questions\/r\u00e9ponses"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/","url":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/","name":"Quick change, changement rapide de costumes","isPartOf":{"@id":"https:\/\/www.magicien-magie.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/#primaryimage"},"image":{"@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/#primaryimage"},"thumbnailUrl":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/changements-rapides.jpg","datePublished":"2021-07-19T06:10:06+00:00","dateModified":"2021-07-19T06:10:10+00:00","author":{"@id":"https:\/\/www.magicien-magie.com\/blog\/#\/schema\/person\/5daf4d489d234d2f5bc62f0d15ca0569"},"description":"Le monde du divertissement est bond\u00e9 d\u2019arts. Il en existe de toutes les sortes. Entre l\u2019illusionnisme, la magie close up et le quick change, les amateurs n\u2019ont pas le temps de s\u2019ennuyer.","breadcrumb":{"@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/#primaryimage","url":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/changements-rapides.jpg","contentUrl":"https:\/\/www.magicien-magie.com\/blog\/wp-content\/uploads\/2021\/07\/changements-rapides.jpg","width":900,"height":600,"caption":"changements rapides"},{"@type":"BreadcrumbList","@id":"https:\/\/www.magicien-magie.com\/blog\/quick-change-ou-transformiste-techniques-et-secrets-de-changement-de-vetements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.magicien-magie.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quick change ou transformiste : techniques et secrets de changement de v\u00eatements"}]},{"@type":"WebSite","@id":"https:\/\/www.magicien-magie.com\/blog\/#website","url":"https:\/\/www.magicien-magie.com\/blog\/","name":"Blog magie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.magicien-magie.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.magicien-magie.com\/blog\/#\/schema\/person\/5daf4d489d234d2f5bc62f0d15ca0569","name":"artiste","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f8d73a44c0c9e30f70e6488629a68a6ad11b4e47e9fe015e6fc8cf625dade1e?s=96&d=mm&r=g","caption":"artiste"},"url":"https:\/\/www.magicien-magie.com\/blog\/author\/artiste\/"}]}},"_links":{"self":[{"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/posts\/274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/comments?post=274"}],"version-history":[{"count":1,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/posts\/274\/revisions"}],"predecessor-version":[{"id":277,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/posts\/274\/revisions\/277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/media\/276"}],"wp:attachment":[{"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/media?parent=274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/categories?post=274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.magicien-magie.com\/blog\/wp-json\/wp\/v2\/tags?post=274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}